{"id":3956,"date":"2022-08-19T14:10:33","date_gmt":"2022-08-19T12:10:33","guid":{"rendered":"https:\/\/www.crispy-links.com\/mentions-legales\/"},"modified":"2025-10-10T15:02:23","modified_gmt":"2025-10-10T13:02:23","slug":"legale-informatie","status":"publish","type":"page","link":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/","title":{"rendered":"Legale informatie"},"content":{"rendered":"<h2 data-source-line=\"9-9\">Article 1 \u2013 MENTIONS L\u00c9GALES<\/h2>\n<p data-source-line=\"11-11\">Le pr\u00e9sent site, accessible \u00e0 l&#8217;URL\u00a0https:\/\/crispy-links.com\/\u00a0(le \u00ab Site \u00bb), est \u00e9dit\u00e9 par :<\/p>\n<p data-source-line=\"13-13\"><strong>BACON VENTURES<\/strong>, SRL au capital de 39 000 euros, inscrite au Registre des Personnes Morales sous le num\u00e9ro BE 1024.232.403, dont le si\u00e8ge social est situ\u00e9 Rue de la Croix Limont 11, 5590 Ciney, Belgique, repr\u00e9sent\u00e9e par Lionel Godefroid et Samuel Szepetiuk, d\u00fbment habilit\u00e9s,<\/p>\n<p data-source-line=\"15-15\">(Ci-apr\u00e8s d\u00e9sign\u00e9 le \u00ab Prestataire \u00bb).<\/p>\n<p data-source-line=\"17-17\">Le num\u00e9ro individuel TVA du Prestataire est : BE 1024.232.403.<\/p>\n<p data-source-line=\"19-19\">Le Site est h\u00e9berg\u00e9 par les soci\u00e9t\u00e9s OVH SAS, situ\u00e9 2 rue Kellermann 59100 Roubaix, France et P4X.<\/p>\n<p data-source-line=\"21-21\">Les Directeurs de la publication du Site sont Lionel Godefroid et Samuel Szepetiuk.<\/p>\n<p data-source-line=\"23-23\">Le Service Client du Prestataire peut \u00eatre contact\u00e9 :<\/p>\n<ul data-source-line=\"25-28\">\n<li data-source-line=\"25-25\">par email en vous adressant \u00e0 sales@crispy-links.com<\/li>\n<li data-source-line=\"26-26\">aux horaires suivants : de lundi \u00e0 vendredi de 9h \u00e0 18h<\/li>\n<li data-source-line=\"27-28\">par le service de messagerie en ligne<\/li>\n<\/ul>\n<h2 data-source-line=\"29-29\">Article 2 \u2013 CHAMP D&#8217;APPLICATION<\/h2>\n<p data-source-line=\"31-31\">Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de services (les \u00ab Conditions G\u00e9n\u00e9rales \u00bb) ont pour objet de d\u00e9finir et de r\u00e9gir les rapports contractuels entre le Prestataire et tout professionnel (un \u00ab Client \u00bb) ayant cr\u00e9\u00e9 un compte et d\u00e9sirant b\u00e9n\u00e9ficier des services propos\u00e9s sur le Site.<\/p>\n<p data-source-line=\"33-33\">La fourniture des services propos\u00e9s aux Clients sur le Site est conditionn\u00e9e \u00e0 l&#8217;acceptation pr\u00e9alable sans restriction ni r\u00e9serve des pr\u00e9sentes Conditions G\u00e9n\u00e9rales.<\/p>\n<p data-source-line=\"35-35\">Les Conditions G\u00e9n\u00e9rales sont mises \u00e0 la disposition des Clients sur le Site o\u00f9 elles sont directement consultables et peuvent \u00e9galement lui \u00eatre communiqu\u00e9es sur simple demande par tout moyen.<\/p>\n<p data-source-line=\"37-37\">Les Conditions G\u00e9n\u00e9rales sont applicables nonobstant toute stipulation contraire figurant dans tous documents \u00e9manant du Client, et notamment dans ses conditions g\u00e9n\u00e9rales d&#8217;achat.<\/p>\n<p data-source-line=\"39-39\">Les Conditions G\u00e9n\u00e9rales sont applicables sous r\u00e9serve de toute stipulation contraire figurant au bon de commande ou \u00e0 des conditions particuli\u00e8res le cas \u00e9ch\u00e9ant conclues entre la Soci\u00e9t\u00e9 et le Client concern\u00e9.<\/p>\n<h2 data-source-line=\"41-41\">Article 3 \u2013 DESCRIPTION DES SERVICES<\/h2>\n<p data-source-line=\"43-43\">Le Site a pour objet la fourniture en ligne des services suivants :<\/p>\n<ul data-source-line=\"45-49\">\n<li data-source-line=\"45-45\">Services de netlinking et cr\u00e9ation de liens entrants (backlinks) de qualit\u00e9<\/li>\n<li data-source-line=\"46-46\">Services d&#8217;optimisation pour les moteurs de recherche (SEO)<\/li>\n<li data-source-line=\"47-47\">Services de citations et de r\u00e9f\u00e9rencements sur les intelligences artificielles<\/li>\n<li data-source-line=\"48-49\">Consulting et accompagnement en strat\u00e9gie de r\u00e9f\u00e9rencement naturel<\/li>\n<\/ul>\n<p data-source-line=\"50-50\">(ci-apr\u00e8s d\u00e9sign\u00e9s les \u00ab Services \u00bb).<\/p>\n<p data-source-line=\"52-52\">Les Services pr\u00e9sent\u00e9s sur le Site font chacun l&#8217;objet d&#8217;un descriptif mentionnant leurs caract\u00e9ristiques essentielles. Cette description est susceptible de comporter des descriptions, photographies et graphismes qui ne sont communiqu\u00e9s qu&#8217;\u00e0 titre illustratif et peuvent \u00eatre modifi\u00e9es\/mises \u00e0 jour sur le Site.<\/p>\n<h2 data-source-line=\"54-54\">Article 4 \u2013 CONDITIONS D&#8217;INSCRIPTION<\/h2>\n<p data-source-line=\"56-56\">Tout Client d\u00e9sirant pleinement b\u00e9n\u00e9ficier du Site et des Services devra :<\/p>\n<ul data-source-line=\"58-62\">\n<li data-source-line=\"58-58\">disposer de la pleine capacit\u00e9 et agir \u00e0 des fins strictement professionnelles ;<\/li>\n<li data-source-line=\"59-59\">cr\u00e9er son espace personnel sur le Site en renseignant les diff\u00e9rents champs du formulaire de cr\u00e9ation d&#8217;un compte (d\u00e9nomination, nom\/pr\u00e9nom du r\u00e9f\u00e9rent, adresse \u00e9lectronique, etc.) ;<\/li>\n<li data-source-line=\"60-60\">confirmer son acceptation des Conditions G\u00e9n\u00e9rales ;<\/li>\n<li data-source-line=\"61-62\">confirmer son inscription.<\/li>\n<\/ul>\n<p data-source-line=\"63-63\">L&#8217;acc\u00e8s aux Services est possible \u00e0 partir d&#8217;un ordinateur, d&#8217;un smartphone ou d&#8217;une tablette en se connectant au Site.<\/p>\n<p data-source-line=\"65-65\">L&#8217;utilisation des Services n\u00e9cessite une connexion \u00e0 internet haut d\u00e9bit et \u00e0 internet mobile le cas \u00e9ch\u00e9ant.<\/p>\n<p data-source-line=\"67-67\">Les Clients font leur affaire personnelle de la mise en place des moyens informatiques et de t\u00e9l\u00e9communication permettant l&#8217;acc\u00e8s au Site.<\/p>\n<p data-source-line=\"69-69\">Lors de la cr\u00e9ation d&#8217;un compte avec courrier \u00e9lectronique, le Client est invit\u00e9 \u00e0 choisir un mot de passe, qui constitue la garantie de la confidentialit\u00e9 des informations qui seront contenues dans son compte.<\/p>\n<p data-source-line=\"71-71\">Aux fins de validation de l&#8217;inscription, le Prestataire adresse au Client un courrier \u00e9lectronique de confirmation \u00e0 l&#8217;adresse email renseign\u00e9e par ce dernier. Le Client proc\u00e8de alors \u00e0 l&#8217;activation de son compte en cliquant sur le lien hypertexte pr\u00e9vu \u00e0 cet effet dans le courrier \u00e9lectronique de confirmation.<\/p>\n<p data-source-line=\"73-73\">Chaque Client garantit la sinc\u00e9rit\u00e9 et l&#8217;exactitude des informations fournies pour les besoins de son inscription, s&#8217;engage \u00e0 lui notifier toute modification ult\u00e9rieure et garantit que lesdites informations ne portent pas atteinte aux droits de tiers.<\/p>\n<p data-source-line=\"75-75\">Le Client peut modifier ces informations, identifiants et mot de passe \u00e0 partir de son compte sur le Site.<\/p>\n<p data-source-line=\"77-77\">Le Client s&#8217;engage \u00e0 ne pas divulguer ou transf\u00e9rer son compte, ses identifiants et mots de passe et est seul responsable de leur utilisation jusqu&#8217;\u00e0 leur d\u00e9sactivation. Il doit informer imm\u00e9diatement le Prestataire de toute perte ou utilisation non autoris\u00e9e de son compte.<\/p>\n<p data-source-line=\"79-79\">Le Prestataire se r\u00e9serve le droit de supprimer le compte de tout Client qui aurait fourni des informations erron\u00e9es.<\/p>\n<h2 data-source-line=\"81-81\">Article 5 \u2013 COMMANDES<\/h2>\n<p data-source-line=\"83-83\">Tout Client d\u00e9sirant b\u00e9n\u00e9ficier des Services en ligne sur le Site devra :<\/p>\n<ul data-source-line=\"85-91\">\n<li data-source-line=\"85-85\">se connecter \u00e0 son compte Client ;<\/li>\n<li data-source-line=\"86-86\">s\u00e9lectionner les Services qu&#8217;il souhaite utiliser ou souscrire ;<\/li>\n<li data-source-line=\"87-87\">renseigner les diff\u00e9rents champs du bon de commande Client (URL cible, mots-cl\u00e9s, domaines souhait\u00e9s, etc.) ;<\/li>\n<li data-source-line=\"88-88\">confirmer son acceptation de la commande des Services ;<\/li>\n<li data-source-line=\"89-89\">choisir son mode de paiement ;<\/li>\n<li data-source-line=\"90-91\">effectuer le paiement des Services.<\/li>\n<\/ul>\n<p data-source-line=\"92-92\">Sauf disposition expresse figurant sur le Site, le Client ne pourra pas modifier sa commande apr\u00e8s l&#8217;avoir valid\u00e9e, laquelle sera ferme et d\u00e9finitive.<\/p>\n<p data-source-line=\"94-94\">D\u00e8s r\u00e9ception du paiement des Services compris dans la commande, le Prestataire adressera au Client un courrier \u00e9lectronique de confirmation de sa commande \u00e0 l&#8217;adresse email renseign\u00e9e par ce dernier.<\/p>\n<p data-source-line=\"96-96\">Le courrier \u00e9lectronique de confirmation de la commande r\u00e9sume les caract\u00e9ristiques essentielles du\/des Service(s) command\u00e9(s), le prix total, et tout autre \u00e9l\u00e9ment pertinent.<\/p>\n<p data-source-line=\"98-98\">En passant commande sur le Site, le Client accepte express\u00e9ment que le Prestataire lui cr\u00e9e une facture \u00e9lectronique dans son espace client. Il pourra toutefois obtenir une facture papier en adressant sa demande au Service Clients.<\/p>\n<p data-source-line=\"100-100\">Pour lutter contre la fraude, le Prestataire ou ses prestataires de paiement peuvent \u00eatre amen\u00e9s \u00e0 demander des justificatifs suppl\u00e9mentaires au Client ou prendre attache avec ce dernier, au moment de l&#8217;acceptation et\/ou de l&#8217;ex\u00e9cution de la commande. En cas de refus non justifi\u00e9 du Client de d\u00e9livrer les informations et\/ou justificatifs demand\u00e9s, le Prestataire se r\u00e9serve le droit de ne pas accepter ou d&#8217;annuler la commande sans que cela ne puisse faire l&#8217;objet d&#8217;une quelconque contestation.<\/p>\n<p data-source-line=\"102-102\">Le Prestataire se r\u00e9serve \u00e9galement le droit de ne pas accepter ou d&#8217;annuler la commande de tout Client qui aurait fourni des informations erron\u00e9es, qui ne proc\u00e8derait pas au paiement des Services, avec lequel existerait un litige relatif au paiement d&#8217;une commande ant\u00e9rieure ou qui pr\u00e9senterait un niveau de commande anormalement \u00e9lev\u00e9.<\/p>\n<h2 data-source-line=\"104-104\">Article 6 \u2013 CONDITIONS TARIFAIRES<\/h2>\n<p data-source-line=\"106-106\">Les Services sont fournis au tarif du Prestataire en vigueur figurant sur le Site au jour de la commande, exprim\u00e9 en euros hors taxes.<\/p>\n<p data-source-line=\"108-109\">En cas de services sp\u00e9cifiques : Les Services sont factur\u00e9s et le prix est exigible en totalit\u00e9 et payable comptant au jour de la signature du bon de commande.<\/p>\n<p data-source-line=\"111-112\">En cas de services \u00e0 ex\u00e9cution successive : Les Services sont factur\u00e9s et le prix est exigible en totalit\u00e9 et payable comptant au jour de la commande pour la p\u00e9riode contractuelle \u00e0 venir.<\/p>\n<p data-source-line=\"114-114\">Le tarif est ferme et ne peut \u00eatre r\u00e9vis\u00e9 pendant la dur\u00e9e d&#8217;ex\u00e9cution des Services, les parties renon\u00e7ant express\u00e9ment \u00e0 se pr\u00e9valoir des dispositions relatives \u00e0 l&#8217;impr\u00e9vision.<\/p>\n<p data-source-line=\"116-116\">Le Prestataire se r\u00e9serve toutefois le droit de modifier ses prix \u00e0 tout moment pour tous Services qui seraient souscrits post\u00e9rieurement \u00e0 cette modification.<\/p>\n<p data-source-line=\"118-118\">Des \u00e9ventuelles r\u00e9ductions de prix, ristournes et remises pourront s&#8217;appliquer aux Services dans des conditions pr\u00e9vues sur le Site ou dans tout autre document qui serait communiqu\u00e9 au Client. En cas de tarif promotionnel, le Prestataire s&#8217;engage \u00e0 appliquer ce tarif \u00e0 toute commande pass\u00e9e durant la p\u00e9riode de la promotion.<\/p>\n<p data-source-line=\"120-120\">En cas de r\u00e8glement anticip\u00e9 par le Client, aucun escompte ne sera pratiqu\u00e9. En aucun cas les paiements ne peuvent \u00eatre suspendus ni faire l&#8217;objet d&#8217;une quelconque compensation sans accord pr\u00e9alable et \u00e9crit entre le Prestataire et le Client.<\/p>\n<p data-source-line=\"122-122\">En cas de retard de paiement, le Prestataire se r\u00e9serve notamment le droit, sans qu&#8217;aucune indemnit\u00e9 ne soit due au Client, de :<\/p>\n<ul data-source-line=\"124-129\">\n<li data-source-line=\"124-124\">exiger le paiement imm\u00e9diat de l&#8217;ensemble des sommes \u00e0 devoir au titre des Services ;<\/li>\n<li data-source-line=\"125-125\">refuser toute nouvelle commande ou exiger pour toute nouvelle commande un paiement comptant ou une garantie ;<\/li>\n<li data-source-line=\"126-126\">r\u00e9duire, suspendre ou annuler l&#8217;acc\u00e8s aux Services, 30 jours apr\u00e8s mise en demeure rest\u00e9e sans effet ;<\/li>\n<li data-source-line=\"127-127\">appliquer des p\u00e9nalit\u00e9s de retard au taux l\u00e9gal en vigueur en Belgique ;<\/li>\n<li data-source-line=\"128-129\">exiger le paiement d&#8217;une indemnit\u00e9 forfaitaire pour frais de recouvrement.<\/li>\n<\/ul>\n<h2 data-source-line=\"130-130\">Article 7 \u2013 MODES DE PAIEMENT<\/h2>\n<p data-source-line=\"132-132\">Le Client reconna\u00eet express\u00e9ment que toute commande effectu\u00e9e sur le Site est une commande avec obligation de paiement, qui n\u00e9cessite le paiement d&#8217;un prix contre la fourniture du Service command\u00e9.<\/p>\n<p data-source-line=\"134-134\">Les commandes peuvent \u00eatre pay\u00e9es en ayant recours \u00e0 l&#8217;un des modes de paiement suivants :<\/p>\n<ul data-source-line=\"136-139\">\n<li data-source-line=\"136-137\">\n<p data-source-line=\"136-136\"><strong>Paiement par carte bancaire<\/strong>\u00a0: Le paiement s&#8217;effectue directement sur les serveurs bancaires s\u00e9curis\u00e9s, les coordonn\u00e9es bancaires du Client ne transitent pas sur le Site. Les coordonn\u00e9es bancaires communiqu\u00e9es lors du paiement sont prot\u00e9g\u00e9es par un proc\u00e9d\u00e9 de cryptage SSL (Secure Socket Layer).<\/p>\n<\/li>\n<li data-source-line=\"138-139\">\n<p data-source-line=\"138-138\"><strong>Paiement par virement bancaire<\/strong>\u00a0: Le Client peut r\u00e9gler sa commande par virement bancaire. Lors de la commande, le Prestataire communiquera les coordonn\u00e9es du compte sur lequel effectuer le virement, ainsi que la r\u00e9f\u00e9rence de commande \u00e0 indiquer dans l&#8217;ordre de virement.<\/p>\n<\/li>\n<\/ul>\n<p data-source-line=\"140-140\">Le cas \u00e9ch\u00e9ant, la commande valid\u00e9e par le Client ne sera consid\u00e9r\u00e9e comme confirm\u00e9e que lorsque le Prestataire aura pu s&#8217;assurer de la validit\u00e9 du r\u00e8glement.<\/p>\n<h2 data-source-line=\"142-142\">Article 8 \u2013 OBLIGATIONS DU PRESTATAIRE<\/h2>\n<p data-source-line=\"144-144\">Le Prestataire s&#8217;engage \u00e0 mettre en \u0153uvre toutes les diligences requises pour l&#8217;ex\u00e9cution des Services et de ses obligations au titre des pr\u00e9sentes Conditions G\u00e9n\u00e9rales, dans le respect des dispositions l\u00e9gales et r\u00e9glementaires belges et europ\u00e9ennes.<\/p>\n<p data-source-line=\"146-146\">Le Prestataire d\u00e9clare disposer des comp\u00e9tences, de l&#8217;exp\u00e9rience et des moyens n\u00e9cessaires pour fournir les Services de netlinking et d&#8217;optimisation SEO, et assumera la pleine responsabilit\u00e9 de l&#8217;ex\u00e9cution des Services.<\/p>\n<p data-source-line=\"148-148\">Le Prestataire s&#8217;efforce d&#8217;assurer l&#8217;acc\u00e8s et le bon fonctionnement du Site vingt-quatre heures sur vingt-quatre, sept jours sur sept.<\/p>\n<p data-source-line=\"150-150\">Le Prestataire ne peut cependant exclure que l&#8217;acc\u00e8s et le fonctionnement du Site soient interrompus notamment en cas de force majeure, de dysfonctionnements des \u00e9quipements ou du r\u00e9seau internet, de d\u00e9faillance des op\u00e9rateurs de t\u00e9l\u00e9communication, d&#8217;interruption de fourniture d&#8217;\u00e9lectricit\u00e9, ou pour des raisons de maintenance.<\/p>\n<p data-source-line=\"152-152\">Le Prestataire se r\u00e9serve le droit d&#8217;apporter au Site et aux Services toutes les modifications et am\u00e9liorations techniques n\u00e9cessaires au bon fonctionnement.<\/p>\n<p data-source-line=\"154-154\">Les interruptions g\u00e9n\u00e9rales et temporaires du Site et des Services seront, dans la mesure du possible, notifi\u00e9es via le Site avant qu&#8217;elles n&#8217;interviennent, sauf lorsque ces interruptions ont un caract\u00e8re d&#8217;urgence.<\/p>\n<h2 data-source-line=\"156-156\">Article 9 \u2013 OBLIGATIONS DU CLIENT<\/h2>\n<p data-source-line=\"158-158\">Chaque Client s&#8217;engage \u00e0 acc\u00e9der et utiliser le Site et les Services de mani\u00e8re loyale et conform\u00e9ment aux lois en vigueur et aux pr\u00e9sentes Conditions G\u00e9n\u00e9rales.<\/p>\n<p data-source-line=\"160-160\">Les donn\u00e9es et informations communiqu\u00e9es par les Clients devront \u00eatre exactes, sinc\u00e8res et loyales et seront communiqu\u00e9es sous leur seule responsabilit\u00e9.<\/p>\n<p data-source-line=\"162-162\">Plus g\u00e9n\u00e9ralement, chaque Client s&#8217;engage \u00e0 :<\/p>\n<ul data-source-line=\"164-169\">\n<li data-source-line=\"164-164\">s&#8217;assurer du respect des obligations l\u00e9gales applicables \u00e0 son statut de professionnel ;<\/li>\n<li data-source-line=\"165-165\">ne pas modifier la nature ou les modalit\u00e9s de fourniture des Services en cours d&#8217;ex\u00e9cution, sauf accord pr\u00e9alable et \u00e9crit du Prestataire ;<\/li>\n<li data-source-line=\"166-166\">verser le prix des Services dans les conditions pr\u00e9vues aux pr\u00e9sentes ;<\/li>\n<li data-source-line=\"167-167\">ne pas diffuser de contenu illicite ou nuisant au bon fonctionnement du Site ;<\/li>\n<li data-source-line=\"168-169\">signaler imm\u00e9diatement au Prestataire toute difficult\u00e9 ou utilisation anormale du Site.<\/li>\n<\/ul>\n<p data-source-line=\"170-170\">Dans l&#8217;hypoth\u00e8se o\u00f9 un Client serait responsable d&#8217;une infraction \u00e0 la l\u00e9gislation en vigueur, le Prestataire se r\u00e9serve le droit de fournir, \u00e0 la demande de toute autorit\u00e9 l\u00e9gitime, tous renseignements permettant l&#8217;identification du Client contrevenant.<\/p>\n<h2 data-source-line=\"172-172\">Article 10 \u2013 R\u00c9CLAMATIONS<\/h2>\n<p data-source-line=\"174-174\">En cas d&#8217;ex\u00e9cution d\u00e9fectueuse des Services, le Client devra notifier le Prestataire et formuler ses griefs dans un d\u00e9lai de quinze (15) jours calendaires suivant la date o\u00f9 il en a eu connaissance, afin de permettre aux parties de parvenir \u00e0 un r\u00e8glement amiable dans un d\u00e9lai de trente (30) jours.<\/p>\n<p data-source-line=\"176-176\">\u00c0 d\u00e9faut de r\u00e8glement amiable et en cas d&#8217;inex\u00e9cution suffisamment grave du Prestataire, le Client pourra r\u00e9silier les Conditions G\u00e9n\u00e9rales et obtenir le cas \u00e9ch\u00e9ant des dommages et int\u00e9r\u00eats.<\/p>\n<h2 data-source-line=\"178-178\">Article 11 \u2013 RESPONSABILIT\u00c9 DU PRESTATAIRE<\/h2>\n<p data-source-line=\"180-180\">Le Prestataire est tenu \u00e0 une obligation de moyens au titre de la fourniture des Services de netlinking et d&#8217;optimisation SEO.<\/p>\n<p data-source-line=\"182-182\">Chaque Client d\u00e9clare \u00eatre inform\u00e9 des contraintes et des limites des r\u00e9seaux Internet et ne pourra rechercher la responsabilit\u00e9 du Prestataire au titre de dysfonctionnements dans l&#8217;acc\u00e8s aux Services ou de l&#8217;inaccessibilit\u00e9 temporaire des Services.<\/p>\n<p data-source-line=\"184-184\">La responsabilit\u00e9 du Prestataire ne saurait \u00eatre engag\u00e9e :<\/p>\n<ul data-source-line=\"186-189\">\n<li data-source-line=\"186-186\">en cas de force majeure ;<\/li>\n<li data-source-line=\"187-187\">dans le cas o\u00f9 les informations communiqu\u00e9es par le Client sont erron\u00e9es ou incompl\u00e8tes ;<\/li>\n<li data-source-line=\"188-189\">en cas d&#8217;incompatibilit\u00e9 avec certains \u00e9quipements informatiques du Client.<\/li>\n<\/ul>\n<p data-source-line=\"190-190\">En tout \u00e9tat de cause, la responsabilit\u00e9 du Prestataire ne peut exc\u00e9der un montant \u00e9gal au prix hors taxes per\u00e7u aupr\u00e8s du Client au titre des Services au cours des douze (12) derniers mois.<\/p>\n<p data-source-line=\"192-192\">Conform\u00e9ment au droit belge, toute action judiciaire d&#8217;un Client \u00e0 l&#8217;\u00e9gard du Prestataire est atteinte par la prescription \u00e0 l&#8217;expiration d&#8217;une dur\u00e9e d&#8217;un (1) an.<\/p>\n<h2 data-source-line=\"194-194\">Article 12 \u2013 SYST\u00c8MES D&#8217;ENREGISTREMENT<\/h2>\n<p data-source-line=\"196-196\">Les registres informatis\u00e9s, conserv\u00e9s dans les syst\u00e8mes informatiques du Prestataire dans des conditions raisonnables de s\u00e9curit\u00e9, seront consid\u00e9r\u00e9s comme les preuves des communications et actions des Clients et du Prestataire.<\/p>\n<p data-source-line=\"198-198\">Chaque Client reconna\u00eet la valeur de preuve des syst\u00e8mes d&#8217;enregistrement automatis\u00e9s du Site et d\u00e9clare renoncer \u00e0 les contester en cas de litige.<\/p>\n<h2 data-source-line=\"200-200\">Article 13 \u2013 DONN\u00c9ES PERSONNELLES<\/h2>\n<p data-source-line=\"202-202\">Pour davantage d&#8217;informations concernant l&#8217;utilisation de donn\u00e9es \u00e0 caract\u00e8re personnel par le Prestataire, veuillez consulter notre Politique de Confidentialit\u00e9 disponible sur le Site, conforme au R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD).<\/p>\n<h2 data-source-line=\"204-204\">Article 14 \u2013 LIENS HYPERTEXTES<\/h2>\n<p data-source-line=\"206-206\">Les liens hypertextes disponibles sur le Site peuvent renvoyer vers des sites tiers. Ils sont fournis uniquement pour la convenance du Client. L&#8217;existence d&#8217;un lien hypertexte ne saurait engager la responsabilit\u00e9 du Prestataire.<\/p>\n<p data-source-line=\"208-208\">Le Client n&#8217;est pas autoris\u00e9 \u00e0 cr\u00e9er des liens hypertextes vers le Site sans autorisation pr\u00e9alable et \u00e9crite du Prestataire.<\/p>\n<h2 data-source-line=\"210-210\">Article 15 \u2013 PROPRI\u00c9T\u00c9 INTELLECTUELLE<\/h2>\n<p data-source-line=\"212-212\">Le Prestataire est seul titulaire de tous les contenus pr\u00e9sents sur le Site, notamment tous textes, images, logos, logiciels, marques, base de donn\u00e9es et autres \u00e9l\u00e9ments prot\u00e9g\u00e9s par les lois belges et internationales relatives \u00e0 la propri\u00e9t\u00e9 intellectuelle.<\/p>\n<p data-source-line=\"214-214\">Aucun des contenus du Site ne pourra \u00eatre modifi\u00e9, reproduit, copi\u00e9, transmis ou exploit\u00e9 sans l&#8217;autorisation pr\u00e9alable et \u00e9crite du Prestataire.<\/p>\n<p data-source-line=\"216-216\">Le Prestataire conc\u00e8de aux Clients un droit non exclusif d&#8217;acc\u00e8s aux contenus du Site dans le cadre d&#8217;une utilisation personnelle et non commerciale.<\/p>\n<h2 data-source-line=\"218-218\">Article 16 \u2013 DUR\u00c9E \u2013 SUSPENSION \u2013 R\u00c9SILIATION<\/h2>\n<p data-source-line=\"220-220\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales sont conclues pour la dur\u00e9e de fourniture des Services.<\/p>\n<p data-source-line=\"222-222\">En cas de services \u00e0 ex\u00e9cution successive, les Conditions G\u00e9n\u00e9rales sont conclues pour une dur\u00e9e initiale mentionn\u00e9e dans le bon de commande, avec reconduction tacite sauf d\u00e9nonciation.<\/p>\n<p data-source-line=\"224-224\">Le Prestataire se r\u00e9serve le droit de suspendre l&#8217;acc\u00e8s d&#8217;un Client au Site en cas de manquement \u00e0 ses obligations.<\/p>\n<p data-source-line=\"226-226\">Les parties pourront r\u00e9silier les Conditions G\u00e9n\u00e9rales de plein droit en cas de manquement grave de l&#8217;autre partie, apr\u00e8s notification et d\u00e9lai de quinze (15) jours pour y rem\u00e9dier.<\/p>\n<h2 data-source-line=\"228-228\">Article 17 \u2013 CONFIDENTIALIT\u00c9<\/h2>\n<p data-source-line=\"230-230\">Chaque partie s&#8217;engage \u00e0 pr\u00e9server la stricte confidentialit\u00e9 de toutes les informations confidentielles re\u00e7ues de l&#8217;autre partie.<\/p>\n<p data-source-line=\"232-232\">Le pr\u00e9sent engagement de confidentialit\u00e9 est valable pendant la dur\u00e9e des pr\u00e9sentes et pendant deux (2) ans suivant leur expiration.<\/p>\n<h2 data-source-line=\"234-234\">Article 18 \u2013 NOTIFICATIONS<\/h2>\n<p data-source-line=\"236-236\">Toute notification sera valablement effectu\u00e9e par lettre recommand\u00e9e ou par courrier \u00e9lectronique aux coordonn\u00e9es de la partie concern\u00e9e.<\/p>\n<p data-source-line=\"238-238\">Tout changement de coordonn\u00e9es devra \u00eatre notifi\u00e9 \u00e0 l&#8217;autre partie.<\/p>\n<h2 data-source-line=\"240-240\">Article 19 \u2013 AUTONOMIE ET ABSENCE DE RENONCIATION<\/h2>\n<p data-source-line=\"242-242\">Si l&#8217;une des stipulations des pr\u00e9sentes Conditions G\u00e9n\u00e9rales \u00e9tait d\u00e9clar\u00e9e nulle, les autres stipulations resteraient en vigueur.<\/p>\n<p data-source-line=\"244-244\">Le fait pour le Prestataire de ne pas se pr\u00e9valoir d&#8217;une stipulation n&#8217;emporte en aucun cas renonciation.<\/p>\n<h2 data-source-line=\"246-246\">Article 20 \u2013 MODIFICATION<\/h2>\n<p data-source-line=\"248-248\">Le Prestataire se r\u00e9serve le droit de modifier \u00e0 tout moment le contenu du Site, les Services et les pr\u00e9sentes Conditions G\u00e9n\u00e9rales.<\/p>\n<p data-source-line=\"250-250\">La version la plus r\u00e9cente des Conditions G\u00e9n\u00e9rales sera toujours disponible sur le Site.<\/p>\n<p data-source-line=\"252-252\">Les modifications substantielles seront port\u00e9es \u00e0 la connaissance des Clients par courrier \u00e9lectronique.<\/p>\n<h2 data-source-line=\"254-254\">Article 21 \u2013 LITIGES<\/h2>\n<p data-source-line=\"256-256\">Les litiges devront \u00eatre r\u00e9solus, dans la mesure du possible, de mani\u00e8re amiable.<\/p>\n<p data-source-line=\"258-258\">\u00c0 d\u00e9faut de r\u00e8glement amiable dans un d\u00e9lai d&#8217;un mois, tous les litiges seront soumis aux tribunaux de Namur, Belgique.<\/p>\n<h2 data-source-line=\"260-260\">Article 22 \u2013 DROIT APPLICABLE &amp; LANGUE DU CONTRAT<\/h2>\n<p data-source-line=\"262-262\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales sont r\u00e9gies par le droit belge. Elles sont r\u00e9dig\u00e9es en langue fran\u00e7aise. En cas de traduction, seul le texte fran\u00e7ais fera foi en cas de litige.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Article 1 \u2013 MENTIONS L\u00c9GALES Le pr\u00e9sent site, accessible \u00e0 l&#8217;URL\u00a0https:\/\/crispy-links.com\/\u00a0(le \u00ab Site \u00bb), est \u00e9dit\u00e9 par : BACON VENTURES, SRL au capital de 39 000 euros, inscrite au Registre des Personnes Morales sous le num\u00e9ro BE 1024.232.403, dont le si\u00e8ge social est situ\u00e9 Rue de la Croix Limont 11, 5590 Ciney, Belgique, repr\u00e9sent\u00e9e par [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-3956","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legale informatie | Cripsy Links<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legale informatie | Cripsy Links\" \/>\n<meta property=\"og:description\" content=\"Article 1 \u2013 MENTIONS L\u00c9GALES Le pr\u00e9sent site, accessible \u00e0 l&#8217;URL\u00a0https:\/\/crispy-links.com\/\u00a0(le \u00ab Site \u00bb), est \u00e9dit\u00e9 par : BACON VENTURES, SRL au capital de 39 000 euros, inscrite au Registre des Personnes Morales sous le num\u00e9ro BE 1024.232.403, dont le si\u00e8ge social est situ\u00e9 Rue de la Croix Limont 11, 5590 Ciney, Belgique, repr\u00e9sent\u00e9e par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Cripsy Links\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T13:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crispy-links.com\/wp-content\/uploads\/2025\/01\/Cripsy_Links-Logo-dark-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/legale-informatie\\\/\",\"url\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/legale-informatie\\\/\",\"name\":\"Legale informatie | Cripsy Links\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#website\"},\"datePublished\":\"2022-08-19T12:10:33+00:00\",\"dateModified\":\"2025-10-10T13:02:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/legale-informatie\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/legale-informatie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/legale-informatie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legale informatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/\",\"name\":\"Cripsy Links\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#organization\",\"name\":\"Crispy Links\",\"alternateName\":\"Crispy-links.com\",\"url\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.crispy-links.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Cripsy_Links-Logo-dark-1.png\",\"contentUrl\":\"https:\\\/\\\/www.crispy-links.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Cripsy_Links-Logo-dark-1.png\",\"width\":540,\"height\":540,\"caption\":\"Crispy Links\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crispy-links.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legale informatie | Cripsy Links","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/","og_locale":"nl_NL","og_type":"article","og_title":"Legale informatie | Cripsy Links","og_description":"Article 1 \u2013 MENTIONS L\u00c9GALES Le pr\u00e9sent site, accessible \u00e0 l&#8217;URL\u00a0https:\/\/crispy-links.com\/\u00a0(le \u00ab Site \u00bb), est \u00e9dit\u00e9 par : BACON VENTURES, SRL au capital de 39 000 euros, inscrite au Registre des Personnes Morales sous le num\u00e9ro BE 1024.232.403, dont le si\u00e8ge social est situ\u00e9 Rue de la Croix Limont 11, 5590 Ciney, Belgique, repr\u00e9sent\u00e9e par [&hellip;]","og_url":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/","og_site_name":"Cripsy Links","article_modified_time":"2025-10-10T13:02:23+00:00","og_image":[{"width":540,"height":540,"url":"https:\/\/www.crispy-links.com\/wp-content\/uploads\/2025\/01\/Cripsy_Links-Logo-dark-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"14 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/","url":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/","name":"Legale informatie | Cripsy Links","isPartOf":{"@id":"https:\/\/www.crispy-links.com\/nl\/#website"},"datePublished":"2022-08-19T12:10:33+00:00","dateModified":"2025-10-10T13:02:23+00:00","breadcrumb":{"@id":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crispy-links.com\/nl\/legale-informatie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.crispy-links.com\/nl\/legale-informatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.crispy-links.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Legale informatie"}]},{"@type":"WebSite","@id":"https:\/\/www.crispy-links.com\/nl\/#website","url":"https:\/\/www.crispy-links.com\/nl\/","name":"Cripsy Links","description":"","publisher":{"@id":"https:\/\/www.crispy-links.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crispy-links.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.crispy-links.com\/nl\/#organization","name":"Crispy Links","alternateName":"Crispy-links.com","url":"https:\/\/www.crispy-links.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.crispy-links.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.crispy-links.com\/wp-content\/uploads\/2025\/01\/Cripsy_Links-Logo-dark-1.png","contentUrl":"https:\/\/www.crispy-links.com\/wp-content\/uploads\/2025\/01\/Cripsy_Links-Logo-dark-1.png","width":540,"height":540,"caption":"Crispy Links"},"image":{"@id":"https:\/\/www.crispy-links.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/pages\/3956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/comments?post=3956"}],"version-history":[{"count":1,"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/pages\/3956\/revisions"}],"predecessor-version":[{"id":3960,"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/pages\/3956\/revisions\/3960"}],"wp:attachment":[{"href":"https:\/\/www.crispy-links.com\/nl\/wp-json\/wp\/v2\/media?parent=3956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}